{"id":6909,"date":"2024-08-19T14:55:10","date_gmt":"2024-08-19T12:55:10","guid":{"rendered":"https:\/\/www.fasty.se\/produkt\/storm-straps\/"},"modified":"2025-09-03T08:39:15","modified_gmt":"2025-09-03T06:39:15","slug":"sangles-anti-tempete","status":"publish","type":"product","link":"https:\/\/www.fasty.se\/fr\/produit\/sangles-anti-tempete\/","title":{"rendered":"Sangles anti-temp\u00eate"},"content":{"rendered":"<p>Nos sangles anti-temp\u00eate sont la solution id\u00e9ale pour s\u00e9curiser votre tente ou votre auvent par tous les temps. Con\u00e7ues avec un souci de durabilit\u00e9 et de qualit\u00e9 sup\u00e9rieure, ces sangles sont fabriqu\u00e9es \u00e0 partir de mat\u00e9riaux robustes capables de r\u00e9sister aux vents violents et aux conditions extr\u00eames. Gr\u00e2ce \u00e0 une installation facile et \u00e0 une sangle r\u00e9glable, nos sangles anti-temp\u00eate garantissent que votre \u00e9quipement reste stable et prot\u00e9g\u00e9, m\u00eame en cas de vents tr\u00e8s forts.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos sangles anti-temp\u00eate sont la solution parfaite pour s\u00e9curiser votre tente ou votre auvent par tous les temps.<\/p>\n","protected":false},"featured_media":4212,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[130],"product_tag":[],"class_list":["post-6909","product","type-product","status-publish","has-post-thumbnail","product_cat-consommateur","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sangles anti-temp\u00eate - Fasty<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fasty.se\/fr\/produit\/sangles-anti-tempete\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sangles anti-temp\u00eate\" \/>\n<meta property=\"og:description\" content=\"Nos sangles anti-temp\u00eate sont la solution parfaite pour s\u00e9curiser votre tente ou votre auvent par tous les temps.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fasty.se\/fr\/produit\/sangles-anti-tempete\/\" \/>\n<meta property=\"og:site_name\" content=\"Fasty\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-03T06:39:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fasty.se\/wp-content\/uploads\/2024\/08\/talt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"612\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fasty.se\\\/fr\\\/produit\\\/sangles-anti-tempete\\\/\",\"url\":\"https:\\\/\\\/www.fasty.se\\\/fr\\\/produit\\\/sangles-anti-tempete\\\/\",\"name\":\"Sangles anti-temp\u00eate - Fasty\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fasty.se\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fasty.se\\\/fr\\\/produit\\\/sangles-anti-tempete\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fasty.se\\\/fr\\\/produit\\\/sangles-anti-tempete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fasty.se\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/talt.jpg\",\"datePublished\":\"2024-08-19T12:55:10+00:00\",\"dateModified\":\"2025-09-03T06:39:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fasty.se\\\/fr\\\/produit\\\/sangles-anti-tempete\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fasty.se\\\/fr\\\/produit\\\/sangles-anti-tempete\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.fasty.se\\\/fr\\\/produit\\\/sangles-anti-tempete\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fasty.se\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/talt.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fasty.se\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/talt.jpg\",\"width\":1024,\"height\":612},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fasty.se\\\/fr\\\/produit\\\/sangles-anti-tempete\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/www.fasty.se\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tous nos produits\",\"item\":\"https:\\\/\\\/www.fasty.se\\\/fr\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sangles anti-temp\u00eate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fasty.se\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.fasty.se\\\/fr\\\/\",\"name\":\"Fasty\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fasty.se\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fasty.se\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fasty.se\\\/fr\\\/#organization\",\"name\":\"Fasty\",\"url\":\"https:\\\/\\\/www.fasty.se\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.fasty.se\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fasty.se\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Fasty_logotyp.svg\",\"contentUrl\":\"https:\\\/\\\/www.fasty.se\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Fasty_logotyp.svg\",\"width\":132,\"height\":38,\"caption\":\"Fasty\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fasty.se\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sangles anti-temp\u00eate - Fasty","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fasty.se\/fr\/produit\/sangles-anti-tempete\/","og_locale":"fr_FR","og_type":"article","og_title":"Sangles anti-temp\u00eate","og_description":"Nos sangles anti-temp\u00eate sont la solution parfaite pour s\u00e9curiser votre tente ou votre auvent par tous les temps.","og_url":"https:\/\/www.fasty.se\/fr\/produit\/sangles-anti-tempete\/","og_site_name":"Fasty","article_modified_time":"2025-09-03T06:39:15+00:00","og_image":[{"width":1024,"height":612,"url":"https:\/\/www.fasty.se\/wp-content\/uploads\/2024\/08\/talt.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fasty.se\/fr\/produit\/sangles-anti-tempete\/","url":"https:\/\/www.fasty.se\/fr\/produit\/sangles-anti-tempete\/","name":"Sangles anti-temp\u00eate - Fasty","isPartOf":{"@id":"https:\/\/www.fasty.se\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fasty.se\/fr\/produit\/sangles-anti-tempete\/#primaryimage"},"image":{"@id":"https:\/\/www.fasty.se\/fr\/produit\/sangles-anti-tempete\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fasty.se\/wp-content\/uploads\/2024\/08\/talt.jpg","datePublished":"2024-08-19T12:55:10+00:00","dateModified":"2025-09-03T06:39:15+00:00","breadcrumb":{"@id":"https:\/\/www.fasty.se\/fr\/produit\/sangles-anti-tempete\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fasty.se\/fr\/produit\/sangles-anti-tempete\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fasty.se\/fr\/produit\/sangles-anti-tempete\/#primaryimage","url":"https:\/\/www.fasty.se\/wp-content\/uploads\/2024\/08\/talt.jpg","contentUrl":"https:\/\/www.fasty.se\/wp-content\/uploads\/2024\/08\/talt.jpg","width":1024,"height":612},{"@type":"BreadcrumbList","@id":"https:\/\/www.fasty.se\/fr\/produit\/sangles-anti-tempete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/www.fasty.se\/fr\/"},{"@type":"ListItem","position":2,"name":"Tous nos produits","item":"https:\/\/www.fasty.se\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"Sangles anti-temp\u00eate"}]},{"@type":"WebSite","@id":"https:\/\/www.fasty.se\/fr\/#website","url":"https:\/\/www.fasty.se\/fr\/","name":"Fasty","description":"","publisher":{"@id":"https:\/\/www.fasty.se\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fasty.se\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.fasty.se\/fr\/#organization","name":"Fasty","url":"https:\/\/www.fasty.se\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fasty.se\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.fasty.se\/wp-content\/uploads\/2024\/07\/Fasty_logotyp.svg","contentUrl":"https:\/\/www.fasty.se\/wp-content\/uploads\/2024\/07\/Fasty_logotyp.svg","width":132,"height":38,"caption":"Fasty"},"image":{"@id":"https:\/\/www.fasty.se\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fasty.se\/fr\/wp-json\/wp\/v2\/product\/6909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fasty.se\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.fasty.se\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fasty.se\/fr\/wp-json\/wp\/v2\/comments?post=6909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fasty.se\/fr\/wp-json\/wp\/v2\/media\/4212"}],"wp:attachment":[{"href":"https:\/\/www.fasty.se\/fr\/wp-json\/wp\/v2\/media?parent=6909"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.fasty.se\/fr\/wp-json\/wp\/v2\/product_brand?post=6909"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.fasty.se\/fr\/wp-json\/wp\/v2\/product_cat?post=6909"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.fasty.se\/fr\/wp-json\/wp\/v2\/product_tag?post=6909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}